{"id":4288,"date":"2026-05-06T10:55:59","date_gmt":"2026-05-06T08:55:59","guid":{"rendered":"https:\/\/www.macardenete.com\/?post_type=evaluador&#038;p=4288"},"modified":"2026-05-06T10:55:59","modified_gmt":"2026-05-06T08:55:59","slug":"tourism-and-hospitality","status":"publish","type":"evaluador","link":"https:\/\/www.macardenete.com\/es\/evaluador\/tourism-and-hospitality\/","title":{"rendered":"Tourism and Hospitality"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","categories":[19],"class_list":["post-4288","evaluador","type-evaluador","status-publish","hentry","category-evaluador-nacional"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.macardenete.com\/es\/wp-json\/wp\/v2\/evaluador\/4288","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.macardenete.com\/es\/wp-json\/wp\/v2\/evaluador"}],"about":[{"href":"https:\/\/www.macardenete.com\/es\/wp-json\/wp\/v2\/types\/evaluador"}],"wp:attachment":[{"href":"https:\/\/www.macardenete.com\/es\/wp-json\/wp\/v2\/media?parent=4288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.macardenete.com\/es\/wp-json\/wp\/v2\/categories?post=4288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}